{"id":7001,"date":"2022-03-04T16:08:26","date_gmt":"2022-03-04T15:08:26","guid":{"rendered":"https:\/\/www.martegaou.com\/politique-de-confidentialite\/"},"modified":"2022-06-17T10:58:28","modified_gmt":"2022-06-17T08:58:28","slug":"datenschutzrichtlinie","status":"publish","type":"page","link":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<section id=\"ls-section-block_621cee06062a8\" class=\"ls-section  page-one p-b-0 has-m-b m-b-10 has-p-t p-t-10\" >\r\n        <div class=\"container container--wide\">\r\n        \n\n<h1 class=\"ls__heading has-text-align-center wp-block-heading\">DATENSCHUTZRICHTLINIE<\/h1>\n\n\r\n    <\/div>\r\n<\/section>\n\n<section id=\"ls-section-block_6229db2645d2a\" class=\"ls-section  page-two  has-background has-color-3-background-color\" >\r\n        <div class=\"container \">\r\n        \n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"ls-paragraph has-color-black-color has-text-color\">Diese Datenschutzrichtlinie beschreibt die personenbezogenen Daten, die gesammelt oder erzeugt (verarbeitet) werden, wenn Sie die Website nutzen. Diese Datenschutzrichtlinie beschreibt die Arten von personenbezogenen Daten, die gesammelt werden, wenn Sie unsere Website nutzen, und wie Ihre personenbezogenen Daten verwendet, weitergegeben und gesch\u00fctzt werden. Sie erkl\u00e4rt auch, welche Wahlm\u00f6glichkeiten Sie in Bezug auf Ihre personenbezogenen Daten haben und wie Sie mit uns in Kontakt treten k\u00f6nnen.<\/p>\n<\/div>\n<\/div>\n\n\r\n    <\/div>\r\n<\/section>\n\n<section id=\"ls-section-block_6229df0445d2c\" class=\"ls-section \" >\r\n        <div class=\"container container--wide\">\r\n        \n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"ls-heading wp-block-heading\">Inhaltsverzeichnis<\/h2>\n\n\n\n<ol class=\"ls-list wp-block-list\"><li><a href=\"#gdpr-1\">Wer wir sind<\/a> <a href=\"#gdpr-1\">?<\/a><\/li><li><a href=\"#gdpr-2\">Verwendung der gesammelten pers\u00f6nlichen Daten<\/a><\/li><li><a href=\"#gdpr-3\">Kommentare<\/a><\/li><li><a href=\"#gdpr-4\">Medien<\/a><\/li><li><a href=\"#gdpr-5\">Kontaktformulare<\/a><\/li><li><a href=\"#gdpr-6\">Verwendung von Cookies<\/a><\/li><li><a href=\"#gdpr-7\">Statistiken und Messung des Publikums<\/a><\/li><li><a href=\"#gdpr-8\">Speicherfristen f\u00fcr Ihre Daten<\/a><\/li><li><a href=\"#gdpr-9\">Die Rechte, die Sie \u00fcber Ihre Daten haben<\/a><\/li><li><a href=\"#gdpr-10\">\u00dcbermittlung Ihrer pers\u00f6nlichen Daten<\/a><\/li><li><a href=\"#gdpr-11\">Wie wir Ihre Daten sch\u00fctzen<\/a><\/li><li><a href=\"#gdpr-12\">Kontaktinformationen<\/a><\/li><\/ol>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-1\">Wer sind wir?<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Entdecken Sie alle unsere Informationen auf der <a href=\"http:\/\/thesauque.geek-tonic.com\/mentions-legales\/\">rechtliche Hinweise<\/a>.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-2\">Verwendung der gesammelten pers\u00f6nlichen Daten<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wir sammeln keine Daten \u00fcber Sie automatisch und direkt.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Dessen ungeachtet k\u00f6nnen wir Informationen, einschlie\u00dflich personenbezogener Informationen, von Dritten sammeln (siehe Abschnitt <a href=\"#gdpr-5\">Cookies<\/a>).<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-3\">Kommentare<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie einen Kommentar auf unserer Website hinterlassen, werden die im Kommentarformular eingetragenen Daten, aber auch Ihre IP-Adresse und der User Agent Ihres Browsers gesammelt, um uns bei der Erkennung unerw\u00fcnschter Kommentare zu helfen.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Eine aus Ihrer E-Mail-Adresse erstellte anonymisierte Zeichenfolge (auch Hash genannt) kann an den Gravatar-Dienst gesendet werden, um zu \u00fcberpr\u00fcfen, ob Sie den Dienst nutzen. Die Datenschutzklauseln des Dienstes <a href=\"https:\/\/automattic.com\/privacy\/\">Gravatar<\/a>sind verf\u00fcgbar. Nachdem Sie Ihren Kommentar freigeschaltet haben, wird Ihr Profilbild neben Ihrem Kommentar \u00f6ffentlich sichtbar sein.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-4\">Medien<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie ein registrierter Nutzer oder eine registrierte Nutzerin sind und Bilder auf die Website hochladen, empfehlen wir Ihnen, keine Bilder hochzuladen, die EXIF-Daten von GPS-Koordinaten enthalten. Die Besucher Ihrer Website k\u00f6nnen aus diesen Bildern Standortdaten herunterladen und extrahieren.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-5\">Kontaktformulare<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Sie k\u00f6nnen uns beim Ausf\u00fcllen eines Formulars Informationen zur Verf\u00fcgung stellen. Diese Informationen werden uns per E-Mail \u00fcbermittelt und nicht anders als in unserem E-Mail-Service gespeichert. Wenn die Informationen zu kommerziellen Zwecken verwendet werden, wird dies am Ende des Formulars angegeben. Wir werden immer Ihre Zustimmung einholen, wenn wir Informationen \u00fcber ein Formular sammeln.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-6\">Verwendung von Cookies<\/h2>\n\n\n\n<p class=\"ls-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-color-1-color\">Was ist ein Cookie?<\/mark><\/strong><\/p>\n\n\n\n<p class=\"ls-paragraph\">Ein Cookie ist eine kleine Datendatei, die auf Ihr Ger\u00e4t \u00fcbertragen und dort gespeichert wird. Konkret erm\u00f6glicht uns ein Cookie zum Beispiel, Ihren Browser oder Ihre Sprache zu erkennen oder Ihre Einstellungen zu speichern. Auf unserer Website werden zwei Arten von Cookies verwendet: &#8222;Sitzungscookies&#8220; und &#8222;dauerhafte Cookies&#8220;. Sitzungscookies verfallen, wenn Sie Ihren Browser schlie\u00dfen, w\u00e4hrend dauerhafte Cookies auf Ihrem Ger\u00e4t verbleiben, nachdem Sie Ihren Browser geschlossen haben, und bei Ihrem n\u00e4chsten Besuch auf unserer Website wieder verwendet werden k\u00f6nnen.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Weitere Informationen \u00fcber <a href=\"https:\/\/www.allaboutcookies.org\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">allaboutcookies.org<\/a>.<\/p>\n\n\n\n<p class=\"ls-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-color-1-color\">Nos Kekse<\/mark><\/strong><\/p>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie einen Kommentar auf unserer Website abgeben, wird Ihnen angeboten, Ihren Namen, Ihre E-Mail-Adresse und Ihre Website in Cookies zu speichern. Dies dient lediglich Ihrer Bequemlichkeit, damit Sie diese Informationen nicht eingeben m\u00fcssen, wenn Sie sp\u00e4ter einen weiteren Kommentar abgeben. Diese Cookies laufen nach einem Jahr ab.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie ein Konto haben und sich auf dieser Website anmelden, wird ein tempor\u00e4res Cookie erstellt, um festzustellen, ob Ihr Browser Cookies akzeptiert. Es enth\u00e4lt keine personenbezogenen Daten und wird automatisch gel\u00f6scht, wenn Sie Ihren Browser schlie\u00dfen.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie sich anmelden, setzen wir eine Reihe von Cookies, um Ihre Anmeldeinformationen und Bildschirmeinstellungen zu speichern. Die Lebensdauer eines Anmelde-Cookies betr\u00e4gt zwei Tage, die eines Cookies f\u00fcr die Bildschirmeinstellungen ein Jahr. Wenn Sie &#8222;An mich erinnern&#8220; ankreuzen, wird Ihr Anmelde-Cookie zwei Wochen lang gespeichert. Wenn Sie sich von Ihrem Konto abmelden, wird das Anmelde-Cookie gel\u00f6scht.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine pers\u00f6nlichen Daten. Es zeigt lediglich die Kennung des Artikels an, den Sie gerade bearbeitet haben. Es l\u00e4uft nach einem Tag ab.<\/p>\n\n\n\n<p class=\"ls-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-color-1-color\">Cookies von Drittanbietern<\/mark><\/strong><\/p>\n\n\n\n<p class=\"ls-paragraph\">Die Artikel auf dieser Website k\u00f6nnen eingebettete Inhalte enthalten (z. B. Videos, Bilder, Artikel \u2026). Von anderen Websites eingebettete Inhalte verhalten sich genauso, als w\u00fcrde der Besucher diese andere Website besuchen.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Diese Websites k\u00f6nnten Daten \u00fcber Sie sammeln, Cookies verwenden, Tracking-Tools von Drittanbietern einbetten und Ihre Interaktionen mit diesen eingebetteten Inhalten verfolgen, wenn Sie ein eingeloggtes Konto auf ihrer Website haben.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Wir k\u00f6nnen bestimmten Gesch\u00e4ftspartnern gestatten, Technologien auf unserer Website zu installieren. Diese Partner setzen diese Technologien ein, um uns bei der Analyse der Art und Weise zu helfen, wie Sie die Website nutzen, z. B. indem sie die Dienste Dritter, \u00fcber die Sie auf die Plattform gelangt sind, bewerten, um unsere Dienste auf unserer Website und auf den Websites Dritter zu vermarkten und zu bewerben, um uns bei der Aufdeckung und Verhinderung von Betrug oder der Durchf\u00fchrung von Risikobewertungen zu unterst\u00fctzen oder um Informationen \u00fcber Ihre Aktivit\u00e4ten auf der Website zu sammeln.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Unsere Website kann Social Plugins verwenden, die von Drittunternehmen bereitgestellt und betrieben werden, wie z. B. die &#8222;Gef\u00e4llt mir&#8220;-Schaltfl\u00e4che von Facebook. Dementsprechend k\u00f6nnen Sie dem Dritten Informationen senden, die Sie in einem bestimmten Bereich unserer Website ansehen. Wenn Sie nicht in Ihr bei der Drittpartei er\u00f6ffnetes Konto eingeloggt sind, kann die Drittpartei Ihre Identit\u00e4t nicht erfahren. Wenn Sie in Ihr Konto bei der Drittpartei eingeloggt sind, kann die Drittpartei die Informationen oder Aktionen, die sich auf Ihre Interaktionen mit unserer Website beziehen, mit Ihrem Konto bei der Drittpartei verkn\u00fcpfen. Bitte lesen Sie die Datenschutzrichtlinien der Drittpartei, um mehr \u00fcber deren Datenpraktiken zu erfahren.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Eine Liste der auf dieser Seite verwendeten Cookies von Drittanbietern finden Sie vom <a href=\"\/#moove_gdpr_cookie_modal\">Cookie-Management-Panel<\/a>.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-7\">Statistiken und Messung des Publikums<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Im Bereich der Analyse arbeiten wir mit Google Analytics, um Informationen \u00fcber die Nutzung unserer Website zu erhalten und diese zu verbessern. Diese Funktion kann \u00fcber das <a href=\"\/#moove_gdpr_cookie_modal\">Cookie-Management-Panel<\/a>.<\/p>\n\n\n\n<p class=\"ls-paragraph\">Um zu verhindern, dass Google Analytics Ihre Informationen zu Analysezwecken verwendet, k\u00f6nnen Sie auch das Browser-Add-on zur Deaktivierung von Google Analytics installieren, indem Sie auf <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a>. Beachten Sie, dass wir keine Kontrolle \u00fcber diesen Deaktivierungslink haben und nicht f\u00fcr die Verf\u00fcgbarkeit oder Richtigkeit dieses Mechanismus verantwortlich sind. Besuchen Siez <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245\" target=\"_blank\" rel=\"noreferrer noopener\">diese Dokumentation<\/a> f\u00fcr weitere Informationen.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-8\">Speicherfristen f\u00fcr Ihre Daten<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie einen Kommentar hinterlassen, werden der Kommentar und seine Metadaten auf unbestimmte Zeit gespeichert. Dadurch werden nachfolgende Kommentare automatisch erkannt und genehmigt, anstatt sie in der Moderationswarteschlange zu belassen.<\/p>\n\n\n\n<p class=\"ls-paragraph\">F\u00fcr Nutzerinnen und Nutzer, die sich auf unserer Website registrieren (sofern dies m\u00f6glich ist), speichern wir auch die in ihrem Profil angegebenen pers\u00f6nlichen Daten. Alle Nutzerinnen und Nutzer k\u00f6nnen ihre pers\u00f6nlichen Informationen (mit Ausnahme ihres Benutzernamens) jederzeit einsehen, \u00e4ndern oder l\u00f6schen. Auch die Verwalter der Website k\u00f6nnen diese Informationen einsehen und \u00e4ndern.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-9\">Die Rechte, die Sie \u00fcber Ihre Daten haben<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie ein Benutzerkonto haben oder Kommentare auf der Website hinterlassen haben, k\u00f6nnen Sie eine Datei anfordern, die alle personenbezogenen Daten enth\u00e4lt, die wir \u00fcber Sie gespeichert haben, einschlie\u00dflich der Daten, die Sie uns zur Verf\u00fcgung gestellt haben. Sie k\u00f6nnen auch verlangen, dass die personenbezogenen Daten \u00fcber Sie gel\u00f6scht werden. Dies gilt nicht f\u00fcr Daten, die zu administrativen, rechtlichen oder Sicherheitszwecken gespeichert werden.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-10\">\u00dcbermittlung Ihrer pers\u00f6nlichen Daten<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Die Kommentare der Besucher k\u00f6nnen mithilfe eines automatisierten Dienstes zur Erkennung unerw\u00fcnschter Kommentare \u00fcberpr\u00fcft werden. Alle personenbezogenen Daten, die wir verarbeiten, werden im Herzen der Europ\u00e4ischen Union verarbeitet.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-11\">Wie wir Ihre Daten sch\u00fctzen<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wir implementieren und aktualisieren st\u00e4ndig die Sicherheit der Website, um Ihre Daten vor unberechtigtem Zugriff, Verlust, Zerst\u00f6rung oder Ver\u00e4nderung zu sch\u00fctzen. Wir arbeiten also daran, Ihre Daten so unangreifbar wie m\u00f6glich zu machen. Da das Internet keine 100%ig sichere Umgebung ist, k\u00f6nnen wir die Sicherheit der \u00dcbertragung oder Speicherung Ihrer Daten nicht vollst\u00e4ndig garantieren.<\/p>\n\n\n\n<h2 class=\"ls-heading wp-block-heading\" id=\"gdpr-12\">Kontaktinformationen<\/h2>\n\n\n\n<p class=\"ls-paragraph\">Wenn Sie Anfragen oder Fragen zu Ihren pers\u00f6nlichen Daten haben, kontaktieren Sie uns bitte unter rgpd@geek-tonic.com, weitere Kontaktinformationen finden Sie in unserem Impressum. Bitte beachten Sie, dass wir Sie m\u00f6glicherweise bitten, Ihre Identit\u00e4t zu \u00fcberpr\u00fcfen, bevor wir weitere Schritte bez\u00fcglich Ihrer Anfrage unternehmen.<\/p>\n<\/div>\n<\/div>\n\n\r\n    <\/div>\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":7656,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"sujet":[],"class_list":["post-7001","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzrichtlinie | Ctoncamping<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzrichtlinie | Ctoncamping\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/\" \/>\n<meta property=\"og:site_name\" content=\"Martegaou\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-17T08:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1901\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/\",\"url\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/\",\"name\":\"Datenschutzrichtlinie | Ctoncamping\",\"isPartOf\":{\"@id\":\"https:\/\/www.martegaou.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg\",\"datePublished\":\"2022-03-04T15:08:26+00:00\",\"dateModified\":\"2022-06-17T08:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage\",\"url\":\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg\",\"contentUrl\":\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg\",\"width\":1901,\"height\":550,\"caption\":\"camping ctoncamping\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Camping Bouches-du-Rh\u00f4ne\",\"item\":\"https:\/\/www.martegaou.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzrichtlinie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.martegaou.com\/#website\",\"url\":\"https:\/\/www.martegaou.com\/\",\"name\":\"Martegaou\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.martegaou.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.martegaou.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.martegaou.com\/#organization\",\"name\":\"Ctoncamping\",\"url\":\"https:\/\/www.martegaou.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.martegaou.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/03\/logo-alt-ctoncamping.png\",\"contentUrl\":\"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/03\/logo-alt-ctoncamping.png\",\"width\":402,\"height\":72,\"caption\":\"Ctoncamping\"},\"image\":{\"@id\":\"https:\/\/www.martegaou.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzrichtlinie | Ctoncamping","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Datenschutzrichtlinie | Ctoncamping","og_url":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/","og_site_name":"Martegaou","article_modified_time":"2022-06-17T08:58:28+00:00","og_image":[{"width":1901,"height":550,"url":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/","url":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/","name":"Datenschutzrichtlinie | Ctoncamping","isPartOf":{"@id":"https:\/\/www.martegaou.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage"},"image":{"@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg","datePublished":"2022-03-04T15:08:26+00:00","dateModified":"2022-06-17T08:58:28+00:00","breadcrumb":{"@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#primaryimage","url":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg","contentUrl":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/06\/camping-ctoncamping.jpg","width":1901,"height":550,"caption":"camping ctoncamping"},{"@type":"BreadcrumbList","@id":"https:\/\/www.martegaou.com\/de\/datenschutzrichtlinie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Camping Bouches-du-Rh\u00f4ne","item":"https:\/\/www.martegaou.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzrichtlinie"}]},{"@type":"WebSite","@id":"https:\/\/www.martegaou.com\/#website","url":"https:\/\/www.martegaou.com\/","name":"Martegaou","description":"","publisher":{"@id":"https:\/\/www.martegaou.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.martegaou.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.martegaou.com\/#organization","name":"Ctoncamping","url":"https:\/\/www.martegaou.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.martegaou.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/03\/logo-alt-ctoncamping.png","contentUrl":"https:\/\/www.martegaou.com\/wp-content\/uploads\/2022\/03\/logo-alt-ctoncamping.png","width":402,"height":72,"caption":"Ctoncamping"},"image":{"@id":"https:\/\/www.martegaou.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/pages\/7001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/comments?post=7001"}],"version-history":[{"count":4,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/pages\/7001\/revisions"}],"predecessor-version":[{"id":7666,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/pages\/7001\/revisions\/7666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/media\/7656"}],"wp:attachment":[{"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/media?parent=7001"}],"wp:term":[{"taxonomy":"sujet","embeddable":true,"href":"https:\/\/www.martegaou.com\/de\/wp-json\/wp\/v2\/sujet?post=7001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}